{"id":88483,"date":"2022-09-27T15:23:19","date_gmt":"2022-09-27T13:23:19","guid":{"rendered":"https:\/\/www.rendez-vous-store.com\/?post_type=product&#038;p=88483"},"modified":"2026-04-24T12:43:48","modified_gmt":"2026-04-24T10:43:48","slug":"comme-des-garcons-wallet-embossed-line-sa310e-marron","status":"publish","type":"product","link":"https:\/\/rendez-vous-store.com\/fr\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/","title":{"rendered":"Comme Des Gar\u00e7ons - Portefeuille Ligne gaufr\u00e9e SA310E - Marron"},"content":{"rendered":"<ul>\n<li>Portefeuille de Comme Des Gar\u00e7ons<\/li>\n<li>Couleur : Marron<\/li>\n<li>Composition : 100% Peau de vache<\/li>\n<li>Dimensions : 11x10cm<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Wallet from Comme Des Gar\u00e7ons Color: Brown Composition: 100% Cow hide Measurements: 11x10cm<\/p>","protected":false},"featured_media":92221,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[20,70],"product_tag":[744],"class_list":{"0":"post-88483","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-men-selection-discover-our-selection-rendez-vous-store","7":"product_cat-accessories-men-rendez-vous-store","8":"product_tag-comme-des-garcons-wallet","9":"entry","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comme Des Gar\u00e7ons - Wallet Embossed Line SA310E - Marron - RENDEZ-VOUS STORE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rendez-vous-store.com\/fr\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comme Des Gar\u00e7ons - Wallet Embossed Line SA310E - Marron - RENDEZ-VOUS STORE\" \/>\n<meta property=\"og:description\" content=\"Wallet from Comme Des Gar\u00e7ons Color: Brown Composition: 100% Cow hide Measurements: 11x10cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rendez-vous-store.com\/fr\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/\" \/>\n<meta property=\"og:site_name\" content=\"RENDEZ-VOUS STORE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-24T10:43:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rendez-vous-store.com\/wp-content\/uploads\/2022\/09\/rdv_cdg_72-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1696\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/\",\"url\":\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/\",\"name\":\"Comme Des Gar\u00e7ons - Wallet Embossed Line SA310E - Marron - RENDEZ-VOUS STORE\",\"isPartOf\":{\"@id\":\"https:\/\/rendez-vous-store.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rendez-vous-store.com\/app\/uploads\/2022\/09\/rdv_cdg_72-scaled.jpg\",\"datePublished\":\"2022-09-27T13:23:19+00:00\",\"dateModified\":\"2026-04-24T10:43:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/#primaryimage\",\"url\":\"https:\/\/rendez-vous-store.com\/app\/uploads\/2022\/09\/rdv_cdg_72-scaled.jpg\",\"contentUrl\":\"https:\/\/rendez-vous-store.com\/app\/uploads\/2022\/09\/rdv_cdg_72-scaled.jpg\",\"width\":1696,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/rendez-vous-store.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.rendez-vous-store.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comme Des Gar\u00e7ons &#8211; Wallet Embossed Line SA310E &#8211; Marron\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rendez-vous-store.com\/#website\",\"url\":\"https:\/\/rendez-vous-store.com\/\",\"name\":\"RENDEZ-VOUS STORE\",\"description\":\"Slow Fashion for Women and Men\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rendez-vous-store.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comme Des Gar\u00e7ons - Wallet Embossed Line SA310E - Marron - RENDEZ-VOUS STORE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rendez-vous-store.com\/fr\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/","og_locale":"fr_FR","og_type":"article","og_title":"Comme Des Gar\u00e7ons - Wallet Embossed Line SA310E - Marron - RENDEZ-VOUS STORE","og_description":"Wallet from Comme Des Gar\u00e7ons Color: Brown Composition: 100% Cow hide Measurements: 11x10cm","og_url":"https:\/\/rendez-vous-store.com\/fr\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/","og_site_name":"RENDEZ-VOUS STORE","article_modified_time":"2026-04-24T10:43:48+00:00","og_image":[{"width":1696,"height":2560,"url":"https:\/\/rendez-vous-store.com\/wp-content\/uploads\/2022\/09\/rdv_cdg_72-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/","url":"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/","name":"Comme Des Gar\u00e7ons - Wallet Embossed Line SA310E - Marron - RENDEZ-VOUS STORE","isPartOf":{"@id":"https:\/\/rendez-vous-store.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/#primaryimage"},"image":{"@id":"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/#primaryimage"},"thumbnailUrl":"https:\/\/rendez-vous-store.com\/app\/uploads\/2022\/09\/rdv_cdg_72-scaled.jpg","datePublished":"2022-09-27T13:23:19+00:00","dateModified":"2026-04-24T10:43:48+00:00","breadcrumb":{"@id":"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/#primaryimage","url":"https:\/\/rendez-vous-store.com\/app\/uploads\/2022\/09\/rdv_cdg_72-scaled.jpg","contentUrl":"https:\/\/rendez-vous-store.com\/app\/uploads\/2022\/09\/rdv_cdg_72-scaled.jpg","width":1696,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/accessories-men-rendez-vous-store\/comme-des-garcons-wallet-embossed-line-sa310e-marron\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rendez-vous-store.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.rendez-vous-store.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Comme Des Gar\u00e7ons &#8211; Wallet Embossed Line SA310E &#8211; Marron"}]},{"@type":"WebSite","@id":"https:\/\/rendez-vous-store.com\/#website","url":"https:\/\/rendez-vous-store.com\/","name":"RENDEZ-VOUS STORE","description":"Slow Fashion for Women and Men","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rendez-vous-store.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/product\/88483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/media\/92221"}],"wp:attachment":[{"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/media?parent=88483"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/product_brand?post=88483"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/product_cat?post=88483"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/product_tag?post=88483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}