{"id":235699,"date":"2026-02-17T14:43:36","date_gmt":"2026-02-17T13:43:36","guid":{"rendered":"https:\/\/rendez-vous-store.com\/?post_type=product&#038;p=235699"},"modified":"2026-04-24T16:53:17","modified_gmt":"2026-04-24T14:53:17","slug":"youmustcreate-u9aac-salba-short-stone-rendez-vous-store","status":"publish","type":"product","link":"https:\/\/rendez-vous-store.com\/fr\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/","title":{"rendered":"YouMustCreate \u2013 U9AAC SALBA SHORT \u2013 STONE"},"content":{"rendered":"<p><strong>YouMustCreate \u2013 U9AAC SALBA SHORT \u2013 STONE<\/strong><\/p>\n<p>Couleur : Gris<\/p>\n<p>Coupe d\u00e9contract\u00e9e<\/p>\n<p>Coupe large<\/p>\n<p>Veste teint\u00e9e<\/p>\n<p>CORDONS DE R\u00c9GLAGE AU BAS<\/p>\n<p>Poches plaqu\u00e9es lat\u00e9rales et dos biais\u00e9es<\/p>\n<p>Fermeture boutonn\u00e9e \u00e0 la taille Cororo<\/p>\n<p>Fermeture \u00e0 glissi\u00e8re<\/p>\n<p>Composition: 80% Coton, 20% Lin<\/p>\n<p>Fabriqu\u00e9 au Portugal<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Les mesures :\u00a0<\/strong><\/p>\n<p>Taille XS : Tour de taille : 36cm, Hanches : 69cm, Cuisse : 41cm, Entrejambe : 36cm, Longueur : 70cm<\/p>\n<p>Taille S : Tour de taille : 38 cm, Hanches : 73 cm, Cuisse : 42 cm, Entrejambe : 37 cm, Longueur : 74 cm<\/p>","protected":false},"excerpt":{"rendered":"<p>YouMustCreate &#8211; U9AAC SALBA SHORT &#8211; STONE Color: Stone Relaxed fit Wide cut Garment dyed Adjustable hem drawcords Angled side and back patch pockets Cororo button waist fastening Zip closure Composition: 80% Cotton, 20% Linen Made in Portugal &nbsp; &nbsp; &nbsp; &nbsp; The measurements:\u00a0 Size XS: Waist: 36cm, Hip: 69cm, Thigh: 41cm, Inseam: 36cm, Length:&hellip; <a class=\"more-link\" href=\"https:\/\/rendez-vous-store.com\/fr\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/\">Continuer la lecture <span class=\"screen-reader-text\">YouMustCreate \u2013 U9AAC SALBA SHORT \u2013 STONE<\/span><\/a><\/p>","protected":false},"featured_media":236375,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[20,1059,73],"product_tag":[1477],"class_list":{"0":"post-235699","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-men-selection-discover-our-selection-rendez-vous-store","7":"product_cat-new-men-rendez-vous-store","8":"product_cat-trousers-shorts-rendez-vous-store","9":"product_tag-youmustcreate-rendez-vous-store","10":"entry","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>YouMustCreate - U9AAC SALBA SHORT - STONE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rendez-vous-store.com\/fr\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"YouMustCreate - U9AAC SALBA SHORT - STONE\" \/>\n<meta property=\"og:description\" content=\"YouMustCreate &#8211; U9AAC SALBA SHORT &#8211; STONE Color: Stone Relaxed fit Wide cut Garment dyed Adjustable hem drawcords Angled side and back patch pockets Cororo button waist fastening Zip closure Composition: 80% Cotton, 20% Linen Made in Portugal &nbsp; &nbsp; &nbsp; &nbsp; The measurements:\u00a0 Size XS: Waist: 36cm, Hip: 69cm, Thigh: 41cm, Inseam: 36cm, Length:&hellip; Continue reading YouMustCreate &#8211; U9AAC SALBA SHORT &#8211; STONE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rendez-vous-store.com\/fr\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/\" \/>\n<meta property=\"og:site_name\" content=\"RENDEZ-VOUS STORE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-24T14:53:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rendez-vous-store.com\/app\/uploads\/2026\/02\/IMG_5163-min-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/\",\"url\":\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/\",\"name\":\"YouMustCreate - U9AAC SALBA SHORT - STONE\",\"isPartOf\":{\"@id\":\"https:\/\/rendez-vous-store.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rendez-vous-store.com\/app\/uploads\/2026\/02\/IMG_5163-min-scaled.webp\",\"datePublished\":\"2026-02-17T13:43:36+00:00\",\"dateModified\":\"2026-04-24T14:53:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/#primaryimage\",\"url\":\"https:\/\/rendez-vous-store.com\/app\/uploads\/2026\/02\/IMG_5163-min-scaled.webp\",\"contentUrl\":\"https:\/\/rendez-vous-store.com\/app\/uploads\/2026\/02\/IMG_5163-min-scaled.webp\",\"width\":1707,\"height\":2560,\"caption\":\"YouMustCreate - U9AAC SALBA SHORT - STONE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/rendez-vous-store.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.rendez-vous-store.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"YouMustCreate &#8211; U9AAC SALBA SHORT &#8211; STONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rendez-vous-store.com\/#website\",\"url\":\"https:\/\/rendez-vous-store.com\/\",\"name\":\"RENDEZ-VOUS STORE\",\"description\":\"Slow Fashion for Women and Men\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rendez-vous-store.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"YouMustCreate - U9AAC SALBA SHORT - STONE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rendez-vous-store.com\/fr\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/","og_locale":"fr_FR","og_type":"article","og_title":"YouMustCreate - U9AAC SALBA SHORT - STONE","og_description":"YouMustCreate &#8211; U9AAC SALBA SHORT &#8211; STONE Color: Stone Relaxed fit Wide cut Garment dyed Adjustable hem drawcords Angled side and back patch pockets Cororo button waist fastening Zip closure Composition: 80% Cotton, 20% Linen Made in Portugal &nbsp; &nbsp; &nbsp; &nbsp; The measurements:\u00a0 Size XS: Waist: 36cm, Hip: 69cm, Thigh: 41cm, Inseam: 36cm, Length:&hellip; Continue reading YouMustCreate &#8211; U9AAC SALBA SHORT &#8211; STONE","og_url":"https:\/\/rendez-vous-store.com\/fr\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/","og_site_name":"RENDEZ-VOUS STORE","article_modified_time":"2026-04-24T14:53:17+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/rendez-vous-store.com\/app\/uploads\/2026\/02\/IMG_5163-min-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/","url":"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/","name":"YouMustCreate - U9AAC SALBA SHORT - STONE","isPartOf":{"@id":"https:\/\/rendez-vous-store.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/#primaryimage"},"image":{"@id":"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/#primaryimage"},"thumbnailUrl":"https:\/\/rendez-vous-store.com\/app\/uploads\/2026\/02\/IMG_5163-min-scaled.webp","datePublished":"2026-02-17T13:43:36+00:00","dateModified":"2026-04-24T14:53:17+00:00","breadcrumb":{"@id":"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/#primaryimage","url":"https:\/\/rendez-vous-store.com\/app\/uploads\/2026\/02\/IMG_5163-min-scaled.webp","contentUrl":"https:\/\/rendez-vous-store.com\/app\/uploads\/2026\/02\/IMG_5163-min-scaled.webp","width":1707,"height":2560,"caption":"YouMustCreate - U9AAC SALBA SHORT - STONE"},{"@type":"BreadcrumbList","@id":"https:\/\/rendez-vous-store.com\/shop\/men-selection-discover-our-selection-rendez-vous-store\/trousers-shorts-rendez-vous-store\/youmustcreate-u9aac-salba-short-stone-rendez-vous-store\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rendez-vous-store.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.rendez-vous-store.com\/shop\/"},{"@type":"ListItem","position":3,"name":"YouMustCreate &#8211; U9AAC SALBA SHORT &#8211; STONE"}]},{"@type":"WebSite","@id":"https:\/\/rendez-vous-store.com\/#website","url":"https:\/\/rendez-vous-store.com\/","name":"RENDEZ-VOUS STORE","description":"Slow Fashion for Women and Men","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rendez-vous-store.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/product\/235699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/media\/236375"}],"wp:attachment":[{"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/media?parent=235699"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/product_brand?post=235699"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/product_cat?post=235699"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rendez-vous-store.com\/fr\/wp-json\/wp\/v2\/product_tag?post=235699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}